{"id":59722,"date":"2022-01-12T16:31:26","date_gmt":"2022-01-12T16:31:26","guid":{"rendered":"http:\/\/www.quintadosilval.pt\/?p=59722"},"modified":"2022-01-12T16:32:33","modified_gmt":"2022-01-12T16:32:33","slug":"fermarsi-al-abile-sopra-grindr-appena-proteggere","status":"publish","type":"post","link":"https:\/\/www.quintadosilval.pt\/en\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/","title":{"rendered":"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy"},"content":{"rendered":"<p><title>Fermarsi al abile sopra Grindr: appena proteggere la tua privacy<\/title><\/p>\n<p>Con milioni di utenti con compiutamente il societa, Grindr e una delle app di appuntamenti piu popolari a causa di uomini lesbica e bisessuali. L\u2019app e stata scagliata nel 2009, rendendola anche antecedente a Tinder. Da in quella occasione, Grindr ha affatto modificato lo scenario pederasta. L\u2019obiettivo di Grindr e mostrare agli uomini della associazione LGBT una spianata sicura di incontri. Per mezzo di l\u2019app gli utenti possono assodare i profili delle persone nelle loro vicinanze, sbagliare messaggi e anelare un colloquio.<\/p>\n<h2>Gli appuntamenti online sono durante lo piuttosto tanto divertenti. Benche, e perennemente abilmente succedere <a href=\"https:\/\/datingrecensore.it\/curvesconnect-recensione\/\">curves connect cos \u0413\u0401<\/a> consapevoli dei potenziali rischi a causa di la privacy associati alle app di appuntamenti appena Grindr.<\/h2>\n<p> Non vogliamo creare panico oppure arrestare alle persone di sfruttare le app di appuntamenti. Vogliamo solitario coprire giacche tu e altri utenti abbiate la capacita di coprire voi stessi e la vostra privacy. Anzitutto durante alcuni Paesi, luogo le leggi locali non accettano la unione LGBT, la moderazione e gravemente prestigioso. Malauguratamente, molti discriminano ancora le persone durante inizio al loro orientamente sessuale, il giacche rende necessarie alcune misure di fiducia.<\/p>\n<p>VPNOverview ha parlato insieme l\u2019esperto Philip Tijsma, cosicche fa parte del COC, un\u2019associazione LGBT autorevole nei Paesi Bassi, e mediante Azza Sultan, direttore affiliato di Grinder for Equality. Poi, abbiamo ideato un indice di suggerimenti verso coloro cosicche prendono sul serio la loro privacy riguardo a Grindr: non associarsi informazioni personali non necessarie, disattiva la tua livello e utilizza un\u2019app di geolocalizzazione falsa passaggio un rivale Android.<!--more--><\/p>\n<h2>Quali rischi della privacy presenta Grindr?<\/h2>\n<p>In molti utenti, Grindr e una piattaforma riguardo a cui possono capitare se stessi escludendo sconcezza. Succedere pederasta e un specifico di evento. Il perche e unito un capace conforto in un puro per cui molti giudicano al momento due uomini affinche si tengono attraverso mano. Purtroppo, c\u2019e sempre un bambino circolo di persone malintenzionate affinche usa Grindr durante i propri scopi. Codesto crea potenziali pericoli per la tua privacy e il tuo agiatezza.<\/p>\n<h2>Prossimo utenti possono rivelare la tua atteggiamento<\/h2>\n<p>Qualora vuoi acquisire il apogeo da Grindr, l\u2019app deve regolarmente parere luogo ti trovi. Il programma utilizza GPS e Wi-Fi verso abbinarti ad prossimo utenti Grindr nella tua piazza geografica. Benche, Grindr, che altre app di appuntamenti popolari, ha diverse vulnerabilita affinche consentono agli estranei di svelare la tua posizione. Ad dimostrazione, l\u2019app sfoggio quanto distante sono i tuoi \u201cabbinamenti\u201d con usanza assai dettagliata. Nel 2014, i ricercatori di Synack Cybersecurity hanno scoperchiato in quanto gli utenti di Grindr potevano speditamente abusare queste informazioni durante mostrare le posizioni di altri utenti. Grindr ha risolto codesto problema consentendo agli utenti di disinnescare la condivisione della atteggiamento. Grindr ha risolto presente questione consentendo agli utenti di disattivare la complicita della postura.<\/p>\n<p>Ad qualsivoglia atteggiamento, uno studio di follow-up canale da Trever Faden ha dimostrato cosicche i ricercatori sulla confidenza informatica potevano ancora trovare le posizioni degli utenti di Grindr, unita ad estranei dati personali. Cio epoca plausibile e laddove gli utenti avevano interdetto la adesione della atteggiamento, fine i dati sulla atteggiamento dell\u2019utente venivano comunque inviati al server di Grindr, luogo potevano essere scoperti. Faden ha fabbricato un luogo web sopra cui gli utenti potevano riconoscere chi li ha bloccati su Grindr. Verso svelare queste informazioni, gli utenti devono semplice registrare il loro reputazione consumatore e password Grindr.<\/p>\n<p>Verso scorta dello studio di Faden, Grindr ha limitato l\u2019accesso ai dati degli utenti perche avevano bloccato prossimo utenti. Inoltre, Grindr ha adagio agli utenti di non sfruttare i loro accessi Grindr in prossimo siti web.<\/p>\n<h2>Gli utenti di Grindr con Paesi per mezzo di normative anti-gay potrebbero succedere con minaccia<\/h2>\n<p>Dato giacche Grindr giacche consente alle persone di circoscrivere la postura esatta degli utenti, i rischi verso la privacy sono molti, particolarmente nei luoghi per cui attuale propensione del sesso e stimato un infrazione. L\u2019omosessualita e attualmente considerata illegale durante 69 Paesi, e alcuni di quei Paesi applicano perfino la pena di trapasso. Capitare un consumatore Grindr per uno di questi posti puo vestire conseguenze estreme. Il direzione egizio, ad campione, ha usato l\u2019app Grindr e la sua privazione di confidenza per scovare e anche catturare i cittadini omosessuale, e se metodologicamente l\u2019omosessualita non e illegittimo con quel borgo. La ressa sopra Marocco ha recentemente seguace per eleggere profili falsi sulle app di incontri che Grindr in scoprirli pubblicando le loro ritratto pubblicamente. Di deduzione, molti uomini gay sono finiti mediante espediente verso una via, rinnegati dalle loro famiglie. Ancora l\u2019Iran ha utilizzato la assenza di fiducia su Grindr a causa di far coincidere gli utenti dell\u2019app. Alla completamento, 200 utenti Grindr sono stati presi durante custodia. Grindr ha allettato di combattere presente minaccia nascondendo la postura utilizzata nell\u2019app, ma questi cambiamenti sono stati bene elusi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6104],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fermarsi al abile sopra Grindr: appena proteggere la tua privacy - Quinta Do Silval<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy - Quinta Do Silval\" \/>\n<meta property=\"og:description\" content=\"[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/\" \/>\n<meta property=\"og:site_name\" content=\"Quinta Do Silval\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T16:31:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-12T16:32:33+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/\",\"url\":\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/\",\"name\":\"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy - Quinta Do Silval\",\"isPartOf\":{\"@id\":\"https:\/\/www.quintadosilval.pt\/#website\"},\"datePublished\":\"2022-01-12T16:31:26+00:00\",\"dateModified\":\"2022-01-12T16:32:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.quintadosilval.pt\/#\/schema\/person\/91082182c7332352c59ae672ed0c9852\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.quintadosilval.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.quintadosilval.pt\/#website\",\"url\":\"https:\/\/www.quintadosilval.pt\/\",\"name\":\"Quinta Do Silval\",\"description\":\"Official Page Quinta do Silval\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.quintadosilval.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.quintadosilval.pt\/#\/schema\/person\/91082182c7332352c59ae672ed0c9852\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.quintadosilval.pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/13e1d3b398f1b72b1f2d7d53a6c64370?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/13e1d3b398f1b72b1f2d7d53a6c64370?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.quintadosilval.pt\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy - Quinta Do Silval","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/","og_locale":"en_US","og_type":"article","og_title":"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy - Quinta Do Silval","og_description":"[&hellip;]","og_url":"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/","og_site_name":"Quinta Do Silval","article_published_time":"2022-01-12T16:31:26+00:00","article_modified_time":"2022-01-12T16:32:33+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/","url":"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/","name":"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy - Quinta Do Silval","isPartOf":{"@id":"https:\/\/www.quintadosilval.pt\/#website"},"datePublished":"2022-01-12T16:31:26+00:00","dateModified":"2022-01-12T16:32:33+00:00","author":{"@id":"https:\/\/www.quintadosilval.pt\/#\/schema\/person\/91082182c7332352c59ae672ed0c9852"},"breadcrumb":{"@id":"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.quintadosilval.pt\/fermarsi-al-abile-sopra-grindr-appena-proteggere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.quintadosilval.pt\/"},{"@type":"ListItem","position":2,"name":"Fermarsi al abile sopra Grindr: appena proteggere la tua privacy"}]},{"@type":"WebSite","@id":"https:\/\/www.quintadosilval.pt\/#website","url":"https:\/\/www.quintadosilval.pt\/","name":"Quinta Do Silval","description":"Official Page Quinta do Silval","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quintadosilval.pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.quintadosilval.pt\/#\/schema\/person\/91082182c7332352c59ae672ed0c9852","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.quintadosilval.pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/13e1d3b398f1b72b1f2d7d53a6c64370?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13e1d3b398f1b72b1f2d7d53a6c64370?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.quintadosilval.pt\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/posts\/59722"}],"collection":[{"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/comments?post=59722"}],"version-history":[{"count":1,"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/posts\/59722\/revisions"}],"predecessor-version":[{"id":59723,"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/posts\/59722\/revisions\/59723"}],"wp:attachment":[{"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/media?parent=59722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/categories?post=59722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.quintadosilval.pt\/en\/wp-json\/wp\/v2\/tags?post=59722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}